{"id":15733,"date":"2019-07-02T21:34:36","date_gmt":"2019-07-02T19:34:36","guid":{"rendered":"http:\/\/www.bell-lloc.org\/projecte-educatiu\/"},"modified":"2021-12-21T16:54:35","modified_gmt":"2021-12-21T15:54:35","slug":"educational-project","status":"publish","type":"page","link":"https:\/\/www.bell-lloc.org\/en\/educational-project\/","title":{"rendered":"Educational project"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-flexible.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-15733","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Educational project - Bell-lloc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bell-lloc.org\/en\/educational-project\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educational project - Bell-lloc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bell-lloc.org\/en\/educational-project\/\" \/>\n<meta property=\"og:site_name\" content=\"Bell-lloc\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-21T15:54:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/educational-project\\\/\",\"url\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/educational-project\\\/\",\"name\":\"Educational project - Bell-lloc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/#website\"},\"datePublished\":\"2019-07-02T19:34:36+00:00\",\"dateModified\":\"2021-12-21T15:54:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/educational-project\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/educational-project\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/educational-project\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educational project\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/\",\"name\":\"Bell-lloc\",\"description\":\"Col\u00b7legi Concertat a Girona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bell-lloc.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educational project - Bell-lloc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bell-lloc.org\/en\/educational-project\/","og_locale":"en_US","og_type":"article","og_title":"Educational project - Bell-lloc","og_url":"https:\/\/www.bell-lloc.org\/en\/educational-project\/","og_site_name":"Bell-lloc","article_modified_time":"2021-12-21T15:54:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bell-lloc.org\/en\/educational-project\/","url":"https:\/\/www.bell-lloc.org\/en\/educational-project\/","name":"Educational project - Bell-lloc","isPartOf":{"@id":"https:\/\/www.bell-lloc.org\/en\/#website"},"datePublished":"2019-07-02T19:34:36+00:00","dateModified":"2021-12-21T15:54:35+00:00","breadcrumb":{"@id":"https:\/\/www.bell-lloc.org\/en\/educational-project\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bell-lloc.org\/en\/educational-project\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bell-lloc.org\/en\/educational-project\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.bell-lloc.org\/en\/"},{"@type":"ListItem","position":2,"name":"Educational project"}]},{"@type":"WebSite","@id":"https:\/\/www.bell-lloc.org\/en\/#website","url":"https:\/\/www.bell-lloc.org\/en\/","name":"Bell-lloc","description":"Col\u00b7legi Concertat a Girona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bell-lloc.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/pages\/15733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/comments?post=15733"}],"version-history":[{"count":3,"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/pages\/15733\/revisions"}],"predecessor-version":[{"id":36142,"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/pages\/15733\/revisions\/36142"}],"wp:attachment":[{"href":"https:\/\/www.bell-lloc.org\/en\/wp-json\/wp\/v2\/media?parent=15733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}