{"id":40126,"date":"2024-03-03T10:34:07","date_gmt":"2024-03-03T09:34:07","guid":{"rendered":"https:\/\/www.bell-lloc.org\/preinscripcions-curs-2023-2024\/"},"modified":"2025-06-19T13:00:04","modified_gmt":"2025-06-19T11:00:04","slug":"preinscripciones-curso-2025-2026","status":"publish","type":"page","link":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/","title":{"rendered":"Preinscripciones curso 2025-2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-flexible.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-40126","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preinscripciones curso 2025-2026 - Bell-lloc<\/title>\n<meta name=\"description\" content=\"Consulta todo lo que ofrecemos desde el Col\u00b7legi Bell-lloc para preinscribir a los alumnos en el curso 2025-2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preinscripciones curso 2025-2026 - Bell-lloc\" \/>\n<meta property=\"og:description\" content=\"Consulta todo lo que ofrecemos desde el Col\u00b7legi Bell-lloc para preinscribir a los alumnos en el curso 2025-2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Bell-lloc\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T11:00:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/preinscripciones-curso-2025-2026\\\/\",\"url\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/preinscripciones-curso-2025-2026\\\/\",\"name\":\"Preinscripciones curso 2025-2026 - Bell-lloc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/#website\"},\"datePublished\":\"2024-03-03T09:34:07+00:00\",\"dateModified\":\"2025-06-19T11:00:04+00:00\",\"description\":\"Consulta todo lo que ofrecemos desde el Col\u00b7legi Bell-lloc para preinscribir a los alumnos en el curso 2025-2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/preinscripciones-curso-2025-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/preinscripciones-curso-2025-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/preinscripciones-curso-2025-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preinscripciones curso 2025-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/\",\"name\":\"Bell-lloc\",\"description\":\"Col\u00b7legi Concertat a Girona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bell-lloc.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preinscripciones curso 2025-2026 - Bell-lloc","description":"Consulta todo lo que ofrecemos desde el Col\u00b7legi Bell-lloc para preinscribir a los alumnos en el curso 2025-2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Preinscripciones curso 2025-2026 - Bell-lloc","og_description":"Consulta todo lo que ofrecemos desde el Col\u00b7legi Bell-lloc para preinscribir a los alumnos en el curso 2025-2026.","og_url":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/","og_site_name":"Bell-lloc","article_modified_time":"2025-06-19T11:00:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/","url":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/","name":"Preinscripciones curso 2025-2026 - Bell-lloc","isPartOf":{"@id":"https:\/\/www.bell-lloc.org\/es\/#website"},"datePublished":"2024-03-03T09:34:07+00:00","dateModified":"2025-06-19T11:00:04+00:00","description":"Consulta todo lo que ofrecemos desde el Col\u00b7legi Bell-lloc para preinscribir a los alumnos en el curso 2025-2026.","breadcrumb":{"@id":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bell-lloc.org\/es\/preinscripciones-curso-2025-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.bell-lloc.org\/es\/"},{"@type":"ListItem","position":2,"name":"Preinscripciones curso 2025-2026"}]},{"@type":"WebSite","@id":"https:\/\/www.bell-lloc.org\/es\/#website","url":"https:\/\/www.bell-lloc.org\/es\/","name":"Bell-lloc","description":"Col\u00b7legi Concertat a Girona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bell-lloc.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/pages\/40126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/comments?post=40126"}],"version-history":[{"count":55,"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/pages\/40126\/revisions"}],"predecessor-version":[{"id":49216,"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/pages\/40126\/revisions\/49216"}],"wp:attachment":[{"href":"https:\/\/www.bell-lloc.org\/es\/wp-json\/wp\/v2\/media?parent=40126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}